{"id":11,"date":"2011-05-04T05:17:57","date_gmt":"2011-05-04T05:17:57","guid":{"rendered":"http:\/\/www.fcn.unp.edu.ar\/sitio\/bibliografia\/?page_id=11"},"modified":"2019-05-27T09:54:26","modified_gmt":"2019-05-27T12:54:26","slug":"alumnos","status":"publish","type":"page","link":"https:\/\/www.fcn.unp.edu.ar\/bibliografia\/alumnos\/","title":{"rendered":"Alumnos"},"content":{"rendered":"<p><strong>Car\u00e1cter de la cursada<\/strong>: obligatorio<\/p>\n<p><strong>Destinatarios<\/strong>: alumnos de 2\u00b0 A\u00f1o de la Carrera de Farmacia y alumnos de primer a\u00f1o de la Licenciatura en Qu\u00edmica. Actividad Optativa\/ electiva de la Carrera de Bioqu\u00edmica<\/p>\n<p><strong>Duraci\u00f3n<\/strong>: 30 horas presenciales, 3 por semana (85% de asistencia, seg\u00fan Reglamento Acad\u00e9mico)<\/p>\n<p><strong>Requisitos<\/strong>: concepto de Qu\u00edmica General; para la promoci\u00f3n se requiere aprobaci\u00f3n de Qu\u00edmica General.<\/p>\n<p><strong><span style=\"text-decoration: underline;\">Contenidos m\u00ednimos<\/span><\/strong><\/p>\n<p>B\u00fasqueda bibliogr\u00e1fica.<\/p>\n<p>Fuentes primarias y fuentes secundarias de informaci\u00f3n.<\/p>\n<p>B\u00fasquedas sistem\u00e1ticas y b\u00fasquedas no sistem\u00e1ticas.<\/p>\n<p>Distintos medios de acceso a las fuentes bibliogr\u00e1ficas.<\/p>\n<p><span style=\"text-decoration: underline;\">\u00a0<\/span><\/p>\n<p><strong><span style=\"text-decoration: underline;\">Requisitos para la obtenci\u00f3n del concepto<\/span><\/strong><\/p>\n<p><strong><span style=\"text-decoration: underline;\">\u00a0<\/span><\/strong><\/p>\n<p><strong><span style=\"text-decoration: underline;\">\u00a0<\/span><\/strong><\/p>\n<p><strong><span style=\"text-decoration: underline;\">\u00a0<\/span><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Car\u00e1cter de la cursada: obligatorio Destinatarios: alumnos de 2\u00b0 A\u00f1o de la Carrera de Farmacia y alumnos de primer a\u00f1o de la Licenciatura en Qu\u00edmica. Actividad Optativa\/ electiva de la Carrera de Bioqu\u00edmica Duraci\u00f3n: 30 horas presenciales, 3 por semana &hellip; <a href=\"https:\/\/www.fcn.unp.edu.ar\/bibliografia\/alumnos\/\">Segu\u00ed leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"footnotes":""},"class_list":["post-11","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.fcn.unp.edu.ar\/bibliografia\/wp-json\/wp\/v2\/pages\/11","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fcn.unp.edu.ar\/bibliografia\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.fcn.unp.edu.ar\/bibliografia\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.fcn.unp.edu.ar\/bibliografia\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fcn.unp.edu.ar\/bibliografia\/wp-json\/wp\/v2\/comments?post=11"}],"version-history":[{"count":1,"href":"https:\/\/www.fcn.unp.edu.ar\/bibliografia\/wp-json\/wp\/v2\/pages\/11\/revisions"}],"predecessor-version":[{"id":534,"href":"https:\/\/www.fcn.unp.edu.ar\/bibliografia\/wp-json\/wp\/v2\/pages\/11\/revisions\/534"}],"wp:attachment":[{"href":"https:\/\/www.fcn.unp.edu.ar\/bibliografia\/wp-json\/wp\/v2\/media?parent=11"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}