{"id":12,"date":"2017-03-02T15:26:55","date_gmt":"2017-03-02T15:26:55","guid":{"rendered":"http:\/\/www.fcn.unp.edu.ar\/sitio\/biologiaevolutiva\/?page_id=12"},"modified":"2024-02-22T04:03:49","modified_gmt":"2024-02-22T04:03:49","slug":"bibliografia","status":"publish","type":"page","link":"https:\/\/www.fcn.unp.edu.ar\/biologiaevolutiva\/index.php\/bibliografia\/","title":{"rendered":"Bibliograf\u00eda"},"content":{"rendered":"<p><a href=\"http:\/\/www.fcn.unp.edu.ar\/sitio\/biologiaevolutiva\/wp-content\/uploads\/2017\/03\/Bibliografia.pdf\">Bibliografia<\/a><\/p>\n\n\n<h3 class=\"wp-block-heading\">Tabla cronoestratigr\u00e1fica Internacional<\/h3>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"http:\/\/www.fcn.unp.edu.ar\/sitio\/biologiaevolutiva\/wp-content\/uploads\/2024\/02\/ChronostratChart2023-04Spanish.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Incrustado de ChronostratChart2023-04Spanish.\"><\/object><a id=\"wp-block-file--media-44b8af60-644c-40d6-b318-e57a3e7b3f94\" href=\"http:\/\/www.fcn.unp.edu.ar\/sitio\/biologiaevolutiva\/wp-content\/uploads\/2024\/02\/ChronostratChart2023-04Spanish.pdf\">ChronostratChart2023-04Spanish<\/a><a href=\"http:\/\/www.fcn.unp.edu.ar\/sitio\/biologiaevolutiva\/wp-content\/uploads\/2024\/02\/ChronostratChart2023-04Spanish.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-44b8af60-644c-40d6-b318-e57a3e7b3f94\">Descarga<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Bibliografia Tabla cronoestratigr\u00e1fica Internacional<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-12","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.fcn.unp.edu.ar\/biologiaevolutiva\/index.php\/wp-json\/wp\/v2\/pages\/12","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fcn.unp.edu.ar\/biologiaevolutiva\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.fcn.unp.edu.ar\/biologiaevolutiva\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.fcn.unp.edu.ar\/biologiaevolutiva\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fcn.unp.edu.ar\/biologiaevolutiva\/index.php\/wp-json\/wp\/v2\/comments?post=12"}],"version-history":[{"count":7,"href":"https:\/\/www.fcn.unp.edu.ar\/biologiaevolutiva\/index.php\/wp-json\/wp\/v2\/pages\/12\/revisions"}],"predecessor-version":[{"id":1577,"href":"https:\/\/www.fcn.unp.edu.ar\/biologiaevolutiva\/index.php\/wp-json\/wp\/v2\/pages\/12\/revisions\/1577"}],"wp:attachment":[{"href":"https:\/\/www.fcn.unp.edu.ar\/biologiaevolutiva\/index.php\/wp-json\/wp\/v2\/media?parent=12"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}